{"id":5091,"date":"2023-03-06T16:40:22","date_gmt":"2023-03-06T16:40:22","guid":{"rendered":"http:\/\/mjarc.com\/2023\/03\/06\/casas-terreas-tudo-o-que-precisa-saber\/"},"modified":"2023-11-27T15:18:38","modified_gmt":"2023-11-27T15:18:38","slug":"casas-terreas-tudo-o-que-precisa-saber","status":"publish","type":"post","link":"https:\/\/mjarc.com\/fr\/casas-terreas-tudo-o-que-precisa-saber\/","title":{"rendered":"Maisons de plain-pied : tout ce qu&rsquo;il faut savoir"},"content":{"rendered":"<p>Construire ou r\u00e9nover une maison de plain-pied, nous aborderons dans cet article quelques avantages et inconv\u00e9nients de cette typologie.<\/p>\n<h3>Histoire des maisons \u00e0 un \u00e9tage au Portugal<\/h3>\n<p>En analysant divers extraits de l&rsquo;histoire, il est possible de percevoir que les maisons \u00e0 un \u00e9tage ont une forte pr\u00e9sence dans l&rsquo;architecture portugaise traditionnelle, en particulier dans la r\u00e9gion de l&rsquo;Alentejo.<br \/>\nSelon Ernesto Veiga de Oliveira et Fernando Galhano, auteurs du livre<a href=\"https:\/\/books.openedition.org\/etnograficapress\/6563\" target=\"_blank\" rel=\"noopener\"> \u00ab\u00a0Arquitectura Tradicional Portuguesa\u00a0\u00bb<\/a>, il s&rsquo;agit d&rsquo;une r\u00e9gion de plaines, de grands centres urbains \u00e9loign\u00e9s les uns des autres, de villes ou de villages tr\u00e8s agglom\u00e9r\u00e9s, avec des traces des \u00e9poques romaine et arabe.<\/p>\n<p>Compte tenu de son histoire et de ses caract\u00e9ristiques, la r\u00e9gion de l&rsquo;Alentejo pr\u00e9sente une forte pr\u00e9sence de maisons de plain-pied blanchies \u00e0 la chaux, qui remontent \u00e0 l&rsquo;\u00e9poque des petites agglom\u00e9rations urbaines, habit\u00e9es par des travailleurs ruraux qui n&rsquo;avaient ni terre ni outils. Par cons\u00e9quent, ils n&rsquo;avaient besoin que d&rsquo;un espace pour le logement et non pour l&rsquo;agriculture.<\/p>\n<h3>Quels sont les avantages des maisons de plain-pied?<\/h3>\n<p>Bien que pendant des ann\u00e9es les maisons \u00e0 un \u00e9tage aient \u00e9t\u00e9 associ\u00e9es aux bas revenus ou aux classes populaires, aujourd&rsquo;hui les maisons \u00e0 un \u00e9tage sont de plus en plus courantes. Pourquoi? Parce que les maisons de plain-pied permettent une meilleure mobilit\u00e9. Mais quels sont ses avantages?<\/p>\n<p>L&rsquo;absence d&rsquo;escaliers assure une meilleure mobilit\u00e9 sans recourir \u00e0 des moyens m\u00e9caniques;<br \/>\nPermet une meilleure articulation des diff\u00e9rents espaces int\u00e9rieurs avec l&rsquo;espace ext\u00e9rieur environnant;<br \/>\nEx\u00e9cution plus rapide des travaux, entre autres;<\/p>\n<h3>Y a-t-il des inconv\u00e9nients \u00e0 construire des maisons \u00e0 un \u00e9tage?<\/h3>\n<p>En g\u00e9n\u00e9ral, les co\u00fbts de construction de maisons \u00e0 un \u00e9tage sont inf\u00e9rieurs, compte tenu de ce qui a \u00e9t\u00e9 dit au point pr\u00e9c\u00e9dent. Cependant, ces avantages peuvent facilement \u00eatre annul\u00e9s si vous ne tenez pas compte de certains aspects:<\/p>\n<p>Taille du terrain &#8211; comme toutes les activit\u00e9s sont maintenant men\u00e9es au m\u00eame niveau, une plus grande zone de construction horizontale est n\u00e9cessaire;<br \/>\nManque d&rsquo;espace ext\u00e9rieur, car il peut \u00eatre n\u00e9cessaire de profiter du terrain pour cr\u00e9er une maison spacieuse et fonctionnelle;<\/p>\n<h3>3 aspects \u00e0 consid\u00e9rer avant de construire une maison de plain-pied<\/h3>\n<p>Construire une maison implique une s\u00e9rie d&rsquo;\u00e9tapes \u00e0 suivre, afin d&rsquo;obtenir la maison que vous avez imagin\u00e9e. Dans le cas des maisons \u00e0 un \u00e9tage, il est important de prendre en compte certains aspects, afin de r\u00e9aliser une maison fonctionnelle et architecturalement int\u00e9ressante.<\/p>\n<div><strong>1. \u00c9tablissez un budget<\/strong><\/div>\n<p>Comme dans d&rsquo;autres domaines de la vie, il est important d&rsquo;\u00e9tablir le montant disponible pour construire votre maison.<br \/>\nIl est \u00e9vident que les co\u00fbts des maisons de plain-pied avec terrain diff\u00e8rent des co\u00fbts d&rsquo;un projet plus simple. Par cons\u00e9quent, vous devez r\u00e9fl\u00e9chir \u00e0 ce que vous souhaitez construire dans votre maison, afin de pouvoir \u00e9tablir un budget proche de la r\u00e9alit\u00e9.<\/p>\n<div><strong>2. Id\u00e9aliser les divisions \u00e0 construire<\/strong><\/div>\n<p>Bien que la disposition des pi\u00e8ces soit horizontale, il est plus facile d&rsquo;int\u00e9grer des espaces dans les maisons de plain-pied. Il est donc important de savoir combien et quelles pi\u00e8ces vous souhaitez avoir dans votre maison. De cette mani\u00e8re, il sera beaucoup plus facile d&rsquo;essayer de respecter le budget \u00e9tabli.<\/p>\n<div><strong>3. Choisissez le bon terrain pour construire votre maison<\/strong><\/div>\n<p>Dans tout processus de construction d&rsquo;une maison, il est important de choisir un terrain adapt\u00e9 au type de construction.<br \/>\nVous avez d\u00e9j\u00e0 id\u00e9alis\u00e9 votre future maison, il est temps de faire appel \u00e0 un architecte. Apr\u00e8s tout, ce sera le professionnel qui vous accompagnera tout au long du processus.<br \/>\nEn plus d&rsquo;\u00e9couter vos besoins et vos id\u00e9es, l&rsquo;architecte vous pr\u00e9sentera les meilleures options pour votre maison en fonction de vos go\u00fbts et de vos pr\u00e9f\u00e9rences. Expliquez-lui donc tous vos doutes et vos priorit\u00e9s.<\/p>\n<div><strong>Vous r\u00eavez d&rsquo;avoir une maison de plain-pied?<\/strong><\/div>\n<p>Comme vous pouvez le constater, il est possible d&rsquo;avoir une maison de plain-pied sans trop de difficult\u00e9s. Vous avez besoin d&rsquo;aide? <a href=\"https:\/\/mjarc.com\/fr\/contacto\/\">Prenez contact avec nous!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Construire ou r\u00e9nover une maison de plain-pied, nous aborderons dans cet article quelques avantages et inconv\u00e9nients de cette typologie. Histoire des maisons \u00e0 un \u00e9tage au Portugal En analysant divers extraits de l&rsquo;histoire, il est possible de percevoir que les maisons \u00e0 un \u00e9tage ont une forte pr\u00e9sence dans l&rsquo;architecture portugaise traditionnelle, en particulier dans [&hellip;]<\/p>\n<p class=\"read-more\"><a class=\"button\" href=\"https:\/\/mjarc.com\/fr\/casas-terreas-tudo-o-que-precisa-saber\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":5092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[32],"tags":[355,356,357,358],"class_list":["post-5091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquitetura-fr","tag-maison-de-plain-pied","tag-construction-fr","tag-architecture-fr","tag-portugal-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maisons de plain-pied : tout ce qu&#039;il faut savoir<\/title>\n<meta name=\"description\" content=\"Vous r\u00eavez d&#039;une maison de plain-pied ? D\u00e9couvrez les avantages et les inconv\u00e9nients de ce type de construction, ainsi que 3 aspects \u00e0 prendre en compte avant de construire. D\u00e9couvrez comment un architecte peut vous aider dans cette d\u00e9marche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maisons de plain-pied : tout ce qu&#039;il faut savoir\" \/>\n<meta property=\"og:description\" content=\"Vous r\u00eavez d&#039;une maison de plain-pied ? D\u00e9couvrez les avantages et les inconv\u00e9nients de ce type de construction, ainsi que 3 aspects \u00e0 prendre en compte avant de construire. D\u00e9couvrez comment un architecte peut vous aider dans cette d\u00e9marche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/\" \/>\n<meta property=\"og:site_name\" content=\"Mjarc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mjarc.arquitectos\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-06T16:40:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-27T15:18:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/casa-terrea-mjarc-arquitectos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"geral@wevolved.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"geral@wevolved.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/\"},\"author\":{\"name\":\"geral@wevolved.com\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/person\\\/ab65ccdc5c8ab87efc504c3b3b718820\"},\"headline\":\"Maisons de plain-pied : tout ce qu&rsquo;il faut savoir\",\"datePublished\":\"2023-03-06T16:40:22+00:00\",\"dateModified\":\"2023-11-27T15:18:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/\"},\"wordCount\":725,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/casa-terrea-mjarc-arquitectos.jpg\",\"keywords\":[\"maison de plain-pied\",\"construction\",\"architecture\",\"Portugal\"],\"articleSection\":[\"Architecture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/\",\"url\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/\",\"name\":\"Maisons de plain-pied : tout ce qu'il faut savoir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/casa-terrea-mjarc-arquitectos.jpg\",\"datePublished\":\"2023-03-06T16:40:22+00:00\",\"dateModified\":\"2023-11-27T15:18:38+00:00\",\"description\":\"Vous r\u00eavez d'une maison de plain-pied ? D\u00e9couvrez les avantages et les inconv\u00e9nients de ce type de construction, ainsi que 3 aspects \u00e0 prendre en compte avant de construire. D\u00e9couvrez comment un architecte peut vous aider dans cette d\u00e9marche.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/casa-terrea-mjarc-arquitectos.jpg\",\"contentUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/casa-terrea-mjarc-arquitectos.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-tudo-o-que-precisa-saber\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maisons de plain-pied : tout ce qu&#8217;il faut savoir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/\",\"name\":\"Mjarc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#organization\",\"name\":\"Mjarc\",\"url\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo_black_1.png\",\"contentUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo_black_1.png\",\"width\":130,\"height\":130,\"caption\":\"Mjarc\"},\"image\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mjarc.arquitectos\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mjarc.arq\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/person\\\/ab65ccdc5c8ab87efc504c3b3b718820\",\"name\":\"geral@wevolved.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cc65f333da34ffbb92fb901af0aefde1.jpg?ver=1778176340\",\"url\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cc65f333da34ffbb92fb901af0aefde1.jpg?ver=1778176340\",\"contentUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cc65f333da34ffbb92fb901af0aefde1.jpg?ver=1778176340\",\"caption\":\"geral@wevolved.com\"},\"sameAs\":[\"http:\\\/\\\/mjarc.com\"],\"url\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/author\\\/geralwevolved-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maisons de plain-pied : tout ce qu'il faut savoir","description":"Vous r\u00eavez d'une maison de plain-pied ? D\u00e9couvrez les avantages et les inconv\u00e9nients de ce type de construction, ainsi que 3 aspects \u00e0 prendre en compte avant de construire. D\u00e9couvrez comment un architecte peut vous aider dans cette d\u00e9marche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/","og_locale":"fr_FR","og_type":"article","og_title":"Maisons de plain-pied : tout ce qu'il faut savoir","og_description":"Vous r\u00eavez d'une maison de plain-pied ? D\u00e9couvrez les avantages et les inconv\u00e9nients de ce type de construction, ainsi que 3 aspects \u00e0 prendre en compte avant de construire. D\u00e9couvrez comment un architecte peut vous aider dans cette d\u00e9marche.","og_url":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/","og_site_name":"Mjarc","article_publisher":"https:\/\/www.facebook.com\/mjarc.arquitectos\/","article_published_time":"2023-03-06T16:40:22+00:00","article_modified_time":"2023-11-27T15:18:38+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/casa-terrea-mjarc-arquitectos.jpg","type":"image\/jpeg"}],"author":"geral@wevolved.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"geral@wevolved.com","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/#article","isPartOf":{"@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/"},"author":{"name":"geral@wevolved.com","@id":"https:\/\/mjarc.com\/fr\/#\/schema\/person\/ab65ccdc5c8ab87efc504c3b3b718820"},"headline":"Maisons de plain-pied : tout ce qu&rsquo;il faut savoir","datePublished":"2023-03-06T16:40:22+00:00","dateModified":"2023-11-27T15:18:38+00:00","mainEntityOfPage":{"@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/"},"wordCount":725,"commentCount":0,"publisher":{"@id":"https:\/\/mjarc.com\/fr\/#organization"},"image":{"@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/#primaryimage"},"thumbnailUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/casa-terrea-mjarc-arquitectos.jpg","keywords":["maison de plain-pied","construction","architecture","Portugal"],"articleSection":["Architecture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/","url":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/","name":"Maisons de plain-pied : tout ce qu'il faut savoir","isPartOf":{"@id":"https:\/\/mjarc.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/#primaryimage"},"image":{"@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/#primaryimage"},"thumbnailUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/casa-terrea-mjarc-arquitectos.jpg","datePublished":"2023-03-06T16:40:22+00:00","dateModified":"2023-11-27T15:18:38+00:00","description":"Vous r\u00eavez d'une maison de plain-pied ? D\u00e9couvrez les avantages et les inconv\u00e9nients de ce type de construction, ainsi que 3 aspects \u00e0 prendre en compte avant de construire. D\u00e9couvrez comment un architecte peut vous aider dans cette d\u00e9marche.","breadcrumb":{"@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/#primaryimage","url":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/casa-terrea-mjarc-arquitectos.jpg","contentUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/casa-terrea-mjarc-arquitectos.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/mjarc.com\/casas-terreas-tudo-o-que-precisa-saber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mjarc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Maisons de plain-pied : tout ce qu&#8217;il faut savoir"}]},{"@type":"WebSite","@id":"https:\/\/mjarc.com\/fr\/#website","url":"https:\/\/mjarc.com\/fr\/","name":"Mjarc","description":"","publisher":{"@id":"https:\/\/mjarc.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mjarc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mjarc.com\/fr\/#organization","name":"Mjarc","url":"https:\/\/mjarc.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mjarc.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/logo_black_1.png","contentUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/logo_black_1.png","width":130,"height":130,"caption":"Mjarc"},"image":{"@id":"https:\/\/mjarc.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mjarc.arquitectos\/","https:\/\/www.instagram.com\/mjarc.arq\/"]},{"@type":"Person","@id":"https:\/\/mjarc.com\/fr\/#\/schema\/person\/ab65ccdc5c8ab87efc504c3b3b718820","name":"geral@wevolved.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mjarc.com\/wp-content\/litespeed\/avatar\/cc65f333da34ffbb92fb901af0aefde1.jpg?ver=1778176340","url":"https:\/\/mjarc.com\/wp-content\/litespeed\/avatar\/cc65f333da34ffbb92fb901af0aefde1.jpg?ver=1778176340","contentUrl":"https:\/\/mjarc.com\/wp-content\/litespeed\/avatar\/cc65f333da34ffbb92fb901af0aefde1.jpg?ver=1778176340","caption":"geral@wevolved.com"},"sameAs":["http:\/\/mjarc.com"],"url":"https:\/\/mjarc.com\/fr\/author\/geralwevolved-com\/"}]}},"_links":{"self":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts\/5091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/comments?post=5091"}],"version-history":[{"count":5,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts\/5091\/revisions"}],"predecessor-version":[{"id":6503,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts\/5091\/revisions\/6503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/media\/5092"}],"wp:attachment":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/media?parent=5091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/categories?post=5091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/tags?post=5091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}