{"id":9360,"date":"2023-12-11T17:41:17","date_gmt":"2023-12-11T17:41:17","guid":{"rendered":"https:\/\/mjarc.com\/?p=9360"},"modified":"2024-01-18T12:44:24","modified_gmt":"2024-01-18T12:44:24","slug":"recuperer-une-maison-ancienne-tout-sur-les-permis","status":"publish","type":"post","link":"https:\/\/mjarc.com\/fr\/recuperer-une-maison-ancienne-tout-sur-les-permis\/","title":{"rendered":"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-weight: 400;\">Lorsqu\u2019on d\u00e9marre un projet de restauration d\u2019une maison ancienne, il est essentiel de comprendre les conditions d\u2019obtention d\u2019un permis. Tout d\u2019abord, assurez-vous que les travaux pr\u00e9vus n\u00e9cessitent un contr\u00f4le. Vous pouvez consulter la liste des <\/span><span style=\"font-weight: 400;\">\u0153uvres exempt\u00e9es de contr\u00f4le pr\u00e9alable ici<\/span><span style=\"font-weight: 400;\">.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-weight: 400;\">La <\/span><span style=\"font-weight: 400;\">communication pr\u00e9alable<\/span><span style=\"font-weight: 400;\"> consiste en une d\u00e9claration qui, lorsqu&rsquo;elle est d\u00fbment pr\u00e9par\u00e9e, autorise l&rsquo;int\u00e9ress\u00e9 \u00e0 poursuivre imm\u00e9diatement certaines activit\u00e9s urbaines apr\u00e8s avoir pay\u00e9 les frais applicables, sans qu&rsquo;il soit n\u00e9cessaire de demander des autorisations suppl\u00e9mentaires. Ce type de proc\u00e9dure permet de r\u00e9aliser plusieurs travaux:<\/span><\/span><\/p>\n<ul style=\"text-align: left;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">construction<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">reconstruction<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">extension<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">changements<\/span><\/li>\n<\/ul>\n<p style=\"text-align: left;\"><b>Dans des contextes dans lesquels:<\/b><\/p>\n<ul style=\"text-align: left;\">\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ils sont situ\u00e9s dans la zone couverte par un lotissement ou un plan d\u00e9taill\u00e9, \u00e0 condition qu&rsquo;il s&rsquo;agisse de travaux de reconstruction n&rsquo;entra\u00eenant pas d&rsquo;augmentation de la hauteur de la fa\u00e7ade ou du nombre d&rsquo;\u00e9tages.<\/span><\/li>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sont li\u00e9s \u00e0 des travaux situ\u00e9s dans une \u00ab Zone de fa\u00e7ade urbaine continue consolid\u00e9e \u00bb, qui sont conformes au plan directeur municipal et qui n&rsquo;entra\u00eenent pas une construction plus haute que la hauteur pr\u00e9dominante des fa\u00e7ades de l&rsquo;alignement de construction du c\u00f4t\u00e9 de la rue. o\u00f9 se trouve la nouvelle construction, entre les deux intersections les plus proches, dans les deux sens.<\/span><\/li>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ils sont li\u00e9s \u00e0 la construction de piscines associ\u00e9es \u00e0 la construction principale.<\/span><\/li>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Avoir \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9 d&rsquo;une information pr\u00e9alable favorable, comme stipul\u00e9 aux termes des paragraphes 2 et 3 de l&rsquo;article 14 du <\/span><a href=\"https:\/\/portaldomunicipe.cm-porto.pt\/documents\/20122\/285710\/Decreto-Lei+n.+136_2014+de+9+de+setembro.pdf\/ab718262-d896-6ce7-72c4-a2b3fa69d1aa?t=1614698481390\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Regulamento Jur\u00eddico da Urbaniza\u00e7\u00e3o e da Edifica\u00e7\u00e3o<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: left;\"><b>Communication pr\u00e9alable des travaux<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ce processus comprend les \u00e9tapes suivantes:<\/span><\/p>\n<ol style=\"text-align: justify;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Soumission de la demande et paiement des frais correspondants par le demandeur<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">V\u00e9rification des documents p\u00e9dagogiques par les services municipaux<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Analyse de la demande par les services municipaux<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Subvention pour les services municipaux<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Calcul des taxes et notification au demandeur du paiement <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Paiement effectu\u00e9 par le demandeur<\/span><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: left;\"><b>Communication pr\u00e9alable des travaux \u2013 proc\u00e9dure simplifi\u00e9e<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400; color: #000000;\">Cette modalit\u00e9 permet au demandeur de notifier les travaux de construction \u00e0 l&rsquo;avance.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-weight: 400;\">Le <\/span><span style=\"font-weight: 400;\">d\u00e9marrage des travaux <\/span><span style=\"font-weight: 400;\"> est autoris\u00e9 apr\u00e8s communication pr\u00e9alable et inform\u00e9e et paiement des redevances applicables \u00e0 l&rsquo;intervention urbaine. Le dossier confirmant la soumission au Conseil municipal et le paiement des taxes sert de titre \u00e0 cette communication pr\u00e9alable.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400; color: #000000;\">Les remplacements de mat\u00e9riaux de rev\u00eatement ext\u00e9rieur ou de toiture qui ne modifient pas l&rsquo;am\u00e9nagement, ainsi que les changements de couleur, sont soumis \u00e0 un processus d&rsquo;instructions simplifi\u00e9 dans leurs proc\u00e9dures.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: left;\"><b>Si le bien est d&rsquo;INT\u00c9R\u00caT PATRIMONIAL&#8230;<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u201cDans le cadre du r\u00f4le de la Division des Mus\u00e9es et du Patrimoine Culturel dans l&rsquo;analyse des demandes d&rsquo;autorisation, il est n\u00e9cessaire que ces services pr\u00e9sentent l&rsquo;aper\u00e7u du b\u00e2timent existant en pi\u00e8ces dessin\u00e9es autonomes, car ces \u00e9l\u00e9ments sont essentiels pour la m\u00e9moire future et aussi pour la sensibilisation aux diff\u00e9rentes valeurs qui ont sous-tendu l&rsquo;inscription du bien dans la Charte du patrimoine PDM: architecturales, artistiques, historiques, paysag\u00e8res \u00e9cologiques, symboliques, culturelles, sociales et techniques scientifiques<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Chaque fois qu&rsquo;un b\u00e2timent est class\u00e9, dans la Charte du patrimoine PDM, comme bien d&rsquo;int\u00e9r\u00eat patrimonial, la demande d&rsquo;autorisation doit \u00eatre accompagn\u00e9e d&rsquo;un relev\u00e9 du b\u00e2timent existant en dessins autonomes, ainsi que d&rsquo;un relev\u00e9 photographique de l&rsquo;int\u00e9rieur et de l&rsquo;ext\u00e9rieur, mettant tous deux en \u00e9vidence les \u00e9l\u00e9ments existants ayant une valeur patrimoniale.\u201d (Portal do Mun\u00edcipe do Porto, 2022)<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: left;\"><b>Op\u00e9rations urbaines impliquant une d\u00e9molition<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La loi n\u00b0 79\/2017, du 18 ao\u00fbt, visant \u00e0 \u00e9tablir des mesures de pr\u00e9servation du patrimoine carrel\u00e9 et qui a modifi\u00e9 le RJUE, \u00e9tablit que les interventions urbaines entra\u00eenant le retrait des carreaux des fa\u00e7ades sont soumises \u00e0 un contr\u00f4le pr\u00e9alable d&rsquo;autorisation. Cela s&rsquo;applique ind\u00e9pendamment du fait qu&rsquo;ils soient utilis\u00e9s dans des espaces publics ou des lieux publics. Dans le cas des op\u00e9rations urbaines d\u00e9crites aux alin\u00e9as a) \u00e0 e) et i) du n\u00b0 2 de l&rsquo;article 4, la d\u00e9molition des fa\u00e7ades recouvertes de tuiles ou leur enl\u00e8vement n\u00e9cessite une autorisation sp\u00e9cifique de la Mairie, et peut faire l&rsquo;objet d&rsquo;un motif de refus, sauf circonstances d\u00fbment justifi\u00e9es et autoris\u00e9es par l&rsquo;absence ou la valeur patrimoniale limit\u00e9e des tuiles.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En revanche, selon les termes d\u00e9finis \u00e0 l&rsquo;article 157 du R\u00e9gime juridique des instruments de gestion territoriale (RJIGT), la <\/span><span style=\"color: #f67828;\"><a style=\"color: #f67828;\" href=\"https:\/\/mjarc.com\/fr\/sauver-les-batiments-de-la-demolition-conservation-et-durabilite-dans-larchitecture\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">d\u00e9molition de b\u00e2timents<\/span><\/a><\/span><span style=\"font-weight: 400;\"> doit \u00eatre autoris\u00e9e lorsque:<\/span><\/p>\n<ol style=\"list-style-type: lower-alpha;\">\n<li><span style=\"font-weight: 400;\">Lorsque cela est n\u00e9cessaire \u00e0 l&rsquo;ex\u00e9cution d&rsquo;un plan d&rsquo;urbanisation ou d&rsquo;un plan d\u00e9taill\u00e9;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Lorsqu&rsquo;il est int\u00e9gr\u00e9 dans une op\u00e9ration de r\u00e9habilitation urbaine, pr\u00e9vue dans le cadre d&rsquo;une unit\u00e9 d&rsquo;ex\u00e9cution ou d&rsquo;un plan intercommunal ou d&rsquo;un plan communal;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Lorsque les b\u00e2timents ne pr\u00e9sentent pas les conditions de s\u00e9curit\u00e9 ou de sant\u00e9 indispensables \u00e0 l&rsquo;usage pour lequel ils sont destin\u00e9s et que leur am\u00e9lioration ou leur r\u00e9paration est techniquement ou \u00e9conomiquement irr\u00e9alisable;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Lorsque les caract\u00e9ristiques architecturales des b\u00e2timents ou leur int\u00e9gration urbaine r\u00e9v\u00e8lent un manque de qualit\u00e9 ou une insuffisance.<\/span><\/li>\n<\/ol>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ainsi, pour les interventions urbaines impliquant la d\u00e9molition de structures, la demande doit inclure un rapport d\u00e9taill\u00e9 sur la propri\u00e9t\u00e9 \u00e0 d\u00e9molir. Ce rapport doit contenir un rapport descriptif, un relev\u00e9 photographique, un relev\u00e9 architectural ou toute autre m\u00e9thode permettant une \u00e9valuation compl\u00e8te du projet de d\u00e9molition. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Les services municipaux peuvent autoriser la d\u00e9molition, pour autant qu&rsquo;elle soit justifi\u00e9e, \u00e0 condition de prendre contact au pr\u00e9alable avec la Division communale du patrimoine culturel. Ce contact vise \u00e0 \u00e9valuer la pertinence pour la Banque de Mat\u00e9riaux des \u00e9l\u00e9ments de construction retir\u00e9s, tels que la ma\u00e7onnerie, le fer forg\u00e9, les tuiles, la menuiserie, entre autres. <\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: left;\"><b>Proc\u00e9dure simplifi\u00e9e<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Outre ce qui est pr\u00e9vu dans la loi n\u00b0 79\/2017 du 18 ao\u00fbt, les travaux impliquant le remplacement des mat\u00e9riaux de rev\u00eatement ext\u00e9rieur ou de rev\u00eatement sont soumis \u00e0 une proc\u00e9dure simplifi\u00e9e, \u00e0 condition qu&rsquo;ils n&rsquo;impliquent pas de modifications dans l&rsquo;implantation, ainsi que changements de couleur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les \u00e9l\u00e9ments p\u00e9dagogiques de cette autorisation comprennent les \u00e9l\u00e9ments pr\u00e9cis\u00e9s dans le formulaire intitul\u00e9 \u00abLicen\u00e7a ou comunica\u00e7\u00e3o pr\u00e9via de obra de edifica\u00e7\u00e3o \u2013 Procedimento simplificado\u00bb, disponible sur le Portail Citoyen. Dans de telles op\u00e9rations d&rsquo;urbanisme, le m\u00e9moire descriptif et la justification doivent toujours mentionner les couleurs, en faisant r\u00e9f\u00e9rence \u00e0 la palette de couleurs RAL ou NCS (Natural Color System), ou, le cas \u00e9ch\u00e9ant, pr\u00e9senter un \u00e9chantillon de la couleur ou du mat\u00e9riau \u00e0 utiliser, dans en plus de d\u00e9tailler les mat\u00e9riaux utilis\u00e9s sur les fa\u00e7ades et la toiture. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><span style=\"color: #808080;\"><b>Les r\u00e9f\u00e9rences<\/b><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #808080; font-size: 10pt;\"><span style=\"font-weight: 400;\">Lei n.\u00ba 79\/2017 &#8211; Di\u00e1rio da Rep\u00fablica n.\u00ba 159\/2017, S\u00e9rie I de 2017-08-18. <\/span><a style=\"color: #808080;\" href=\"https:\/\/diariodarepublica.pt\/dr\/detalhe\/lei\/79-2017-108016474\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">https:\/\/diariodarepublica.pt\/dr\/detalhe\/lei\/79-2017-108016474<\/span><\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #808080; font-size: 10pt;\"><span style=\"font-weight: 400;\">Lei n.\u00ba 79\/2017 &#8211; Di\u00e1rio da Rep\u00fablica n.\u00ba 291\/1999, S\u00e9rie I-A de 1999-12-16. <\/span><a style=\"color: #808080;\" href=\"https:\/\/diariodarepublica.pt\/dr\/detalhe\/decreto-lei\/555-1999-655682\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">https:\/\/diariodarepublica.pt\/dr\/detalhe\/decreto-lei\/555-1999-655682<\/span><\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #808080; font-size: 10pt;\"><span style=\"font-weight: 400;\">Portal do Mun\u00edcipe do Porto. (2022, abril). Manual de Recomenda\u00e7\u00f5es e Boas Pr\u00e1ticas. <\/span><i><span style=\"font-weight: 400;\">Portal do Mun\u00edcipe<\/span><\/i><span style=\"font-weight: 400;\">. <\/span><a style=\"color: #808080;\" href=\"https:\/\/portaldomunicipe.cm-porto.pt\/documents\/20122\/285710\/Manual+de+recomenda%C3%A7%C3%B5es+e+boas+pr%C3%A1ticas_Urbanismo.pdf\/be357cfc-9946-5993-8ef4-2dc5c12a435b?t=1678799965877\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">https:\/\/portaldomunicipe.cm-porto.pt\/documents\/20122\/285710\/Manual+de+recomenda%C3%A7%C3%B5es+e+boas+pr%C3%A1ticas_Urbanismo.pdf\/be357cfc-9946-5993-8ef4-2dc5c12a435b?t=1678799965877<\/span><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsqu\u2019on d\u00e9marre un projet de restauration d\u2019une maison ancienne, il est essentiel de comprendre les conditions d\u2019obtention d\u2019un permis. Tout d\u2019abord, assurez-vous que les travaux pr\u00e9vus n\u00e9cessitent un contr\u00f4le. Vous pouvez consulter la liste des \u0153uvres exempt\u00e9es de contr\u00f4le pr\u00e9alable ici. La communication pr\u00e9alable consiste en une d\u00e9claration qui, lorsqu&rsquo;elle est d\u00fbment pr\u00e9par\u00e9e, autorise l&rsquo;int\u00e9ress\u00e9 [&hellip;]<\/p>\n<p class=\"read-more\"><a class=\"button\" href=\"https:\/\/mjarc.com\/fr\/recuperer-une-maison-ancienne-tout-sur-les-permis\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":9344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[32],"tags":[320,323,339,340,341,365],"class_list":["post-9360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquitetura-fr","tag-sauver","tag-demolition","tag-maisons-anciennes","tag-vieilles-maisons","tag-rehabilitation-fr","tag-rehabilitation-urbaine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis - Mjarc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis - Mjarc\" \/>\n<meta property=\"og:description\" content=\"Lorsqu\u2019on d\u00e9marre un projet de restauration d\u2019une maison ancienne, il est essentiel de comprendre les conditions d\u2019obtention d\u2019un permis. Tout d\u2019abord, assurez-vous que les travaux pr\u00e9vus n\u00e9cessitent un contr\u00f4le. Vous pouvez consulter la liste des \u0153uvres exempt\u00e9es de contr\u00f4le pr\u00e9alable ici. La communication pr\u00e9alable consiste en une d\u00e9claration qui, lorsqu&rsquo;elle est d\u00fbment pr\u00e9par\u00e9e, autorise l&rsquo;int\u00e9ress\u00e9 [&hellip;]Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/\" \/>\n<meta property=\"og:site_name\" content=\"Mjarc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mjarc.arquitectos\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-11T17:41:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-18T12:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/12\/recuperar_casa_mjarc-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2051\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mjarc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mjarc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/\"},\"author\":{\"name\":\"Mjarc\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/person\\\/4b3afbd73b7217bd7abd6435d1e05f2e\"},\"headline\":\"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis\",\"datePublished\":\"2023-12-11T17:41:17+00:00\",\"dateModified\":\"2024-01-18T12:44:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/\"},\"wordCount\":1300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/recuperar_casa_mjarc-1-scaled.jpg\",\"keywords\":[\"sauver\",\"demolition\",\"maisons anciennes\",\"vieilles maisons\",\"rehabilitation\",\"R\u00e9habilitation urbaine\"],\"articleSection\":[\"Architecture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/\",\"url\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/\",\"name\":\"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis - Mjarc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/recuperar_casa_mjarc-1-scaled.jpg\",\"datePublished\":\"2023-12-11T17:41:17+00:00\",\"dateModified\":\"2024-01-18T12:44:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/recuperar_casa_mjarc-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/recuperar_casa_mjarc-1-scaled.jpg\",\"width\":2560,\"height\":2051,\"caption\":\"Recuperar Casa - O que necessita de saber com a MJARC Arquitectos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/recuperar-casa-antiga-tudo-sobre-as-licencas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/\",\"name\":\"Mjarc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#organization\",\"name\":\"Mjarc\",\"url\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo_black_1.png\",\"contentUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo_black_1.png\",\"width\":130,\"height\":130,\"caption\":\"Mjarc\"},\"image\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mjarc.arquitectos\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mjarc.arq\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/person\\\/4b3afbd73b7217bd7abd6435d1e05f2e\",\"name\":\"Mjarc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/litespeed\\\/avatar\\\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963\",\"url\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/litespeed\\\/avatar\\\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963\",\"contentUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/litespeed\\\/avatar\\\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963\",\"caption\":\"Mjarc\"},\"url\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/author\\\/mjarc1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis - Mjarc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis - Mjarc","og_description":"Lorsqu\u2019on d\u00e9marre un projet de restauration d\u2019une maison ancienne, il est essentiel de comprendre les conditions d\u2019obtention d\u2019un permis. Tout d\u2019abord, assurez-vous que les travaux pr\u00e9vus n\u00e9cessitent un contr\u00f4le. Vous pouvez consulter la liste des \u0153uvres exempt\u00e9es de contr\u00f4le pr\u00e9alable ici. La communication pr\u00e9alable consiste en une d\u00e9claration qui, lorsqu&rsquo;elle est d\u00fbment pr\u00e9par\u00e9e, autorise l&rsquo;int\u00e9ress\u00e9 [&hellip;]Lire la suite","og_url":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/","og_site_name":"Mjarc","article_publisher":"https:\/\/www.facebook.com\/mjarc.arquitectos\/","article_published_time":"2023-12-11T17:41:17+00:00","article_modified_time":"2024-01-18T12:44:24+00:00","og_image":[{"width":2560,"height":2051,"url":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/12\/recuperar_casa_mjarc-1-scaled.jpg","type":"image\/jpeg"}],"author":"Mjarc","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mjarc","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/#article","isPartOf":{"@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/"},"author":{"name":"Mjarc","@id":"https:\/\/mjarc.com\/fr\/#\/schema\/person\/4b3afbd73b7217bd7abd6435d1e05f2e"},"headline":"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis","datePublished":"2023-12-11T17:41:17+00:00","dateModified":"2024-01-18T12:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/"},"wordCount":1300,"commentCount":0,"publisher":{"@id":"https:\/\/mjarc.com\/fr\/#organization"},"image":{"@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/#primaryimage"},"thumbnailUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/12\/recuperar_casa_mjarc-1-scaled.jpg","keywords":["sauver","demolition","maisons anciennes","vieilles maisons","rehabilitation","R\u00e9habilitation urbaine"],"articleSection":["Architecture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/","url":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/","name":"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis - Mjarc","isPartOf":{"@id":"https:\/\/mjarc.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/#primaryimage"},"image":{"@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/#primaryimage"},"thumbnailUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/12\/recuperar_casa_mjarc-1-scaled.jpg","datePublished":"2023-12-11T17:41:17+00:00","dateModified":"2024-01-18T12:44:24+00:00","breadcrumb":{"@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/#primaryimage","url":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/12\/recuperar_casa_mjarc-1-scaled.jpg","contentUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/12\/recuperar_casa_mjarc-1-scaled.jpg","width":2560,"height":2051,"caption":"Recuperar Casa - O que necessita de saber com a MJARC Arquitectos"},{"@type":"BreadcrumbList","@id":"https:\/\/mjarc.com\/recuperar-casa-antiga-tudo-sobre-as-licencas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mjarc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9cup\u00e9rer une maison ancienne \u2013 tout sur les permis"}]},{"@type":"WebSite","@id":"https:\/\/mjarc.com\/fr\/#website","url":"https:\/\/mjarc.com\/fr\/","name":"Mjarc","description":"","publisher":{"@id":"https:\/\/mjarc.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mjarc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mjarc.com\/fr\/#organization","name":"Mjarc","url":"https:\/\/mjarc.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mjarc.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/logo_black_1.png","contentUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/logo_black_1.png","width":130,"height":130,"caption":"Mjarc"},"image":{"@id":"https:\/\/mjarc.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mjarc.arquitectos\/","https:\/\/www.instagram.com\/mjarc.arq\/"]},{"@type":"Person","@id":"https:\/\/mjarc.com\/fr\/#\/schema\/person\/4b3afbd73b7217bd7abd6435d1e05f2e","name":"Mjarc","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mjarc.com\/wp-content\/litespeed\/avatar\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963","url":"https:\/\/mjarc.com\/wp-content\/litespeed\/avatar\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963","contentUrl":"https:\/\/mjarc.com\/wp-content\/litespeed\/avatar\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963","caption":"Mjarc"},"url":"https:\/\/mjarc.com\/fr\/author\/mjarc1\/"}]}},"_links":{"self":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts\/9360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/comments?post=9360"}],"version-history":[{"count":5,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts\/9360\/revisions"}],"predecessor-version":[{"id":10107,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts\/9360\/revisions\/10107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/media\/9344"}],"wp:attachment":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/media?parent=9360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/categories?post=9360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/tags?post=9360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}