{"id":9465,"date":"2023-11-22T15:13:31","date_gmt":"2023-11-22T15:13:31","guid":{"rendered":"https:\/\/mjarc.com\/maisons-modernes-a-un-etage-exemples-materiaux-et-certification\/"},"modified":"2023-12-14T12:33:36","modified_gmt":"2023-12-14T12:33:36","slug":"maisons-modernes-a-un-etage-exemples-materiaux-et-certification","status":"publish","type":"post","link":"https:\/\/mjarc.com\/fr\/maisons-modernes-a-un-etage-exemples-materiaux-et-certification\/","title":{"rendered":"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification"},"content":{"rendered":"<p>Lorsqu\u2019on envisage de construire une maison, plusieurs points de d\u00e9cision cruciaux se posent. L\u2019une des plus importantes consiste \u00e0 d\u00e9finir le projet de logement : quelle sera sa taille, combien de chambres et de salles de bains il comprendra, s\u2019il aura un jardin et s\u2019il s\u2019agira d\u2019une maison de plain-pied ou plus.<\/p>\n<p>Dans cet article, nous explorons en d\u00e9tail le concept de maisons \u00e0 un \u00e9tage, en mettant en \u00e9vidence des exemples et quelques d\u00e9tails techniques, notamment les mat\u00e9riaux de construction et les certifications pour la construction d&rsquo;une maison moderne \u00e0 un \u00e9tage.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #000000;\">Que sont les maisons de plain-pied?<\/span><\/h3>\n<p>Les maisons \u00e0 un \u00e9tage se caract\u00e9risent par leur simplicit\u00e9 et leur praticit\u00e9, car elles sont construites sur un seul niveau, sans escalier ni marche. Essentiellement, ils se caract\u00e9risent par leur proximit\u00e9 avec le sol, offrant un environnement accessible et fonctionnel pour tous les \u00e2ges.<\/p>\n<p>Les maisons modernes \u00e0 un \u00e9tage sont reconnues pour leur design minimaliste, caract\u00e9ris\u00e9 par des lignes droites qui cr\u00e9ent une atmosph\u00e8re \u00e9pur\u00e9e et moderne. De plus, ces maisons constituent une excellente alternative pour ceux qui souhaitent des espaces avec une mobilit\u00e9 libre et une relation directe avec l&rsquo;ext\u00e9rieur.<\/p>\n<p>L&rsquo;un des principaux avantages des maisons \u00e0 un \u00e9tage est leur accessibilit\u00e9, elles sont id\u00e9ales pour les personnes \u00e0 mobilit\u00e9 r\u00e9duite, les jeunes enfants ou les animaux domestiques, \u00e9vitant les difficult\u00e9s de monter et descendre les escaliers.<\/p>\n<p>&nbsp;<\/p>\n<h3>Exemples de Maisons Modernes \u00e0 un \u00e9tage<\/h3>\n<p><a href=\"https:\/\/mjarc.com\/fr\/projets-architecture\/casa-no-vale-do-douro-projeto-arquitetura\/\" target=\"_blank\" rel=\"noopener\"><strong>Maison Vall\u00e9e du Douro &#8211; MJARC<\/strong><\/a><\/p>\n<p>La volont\u00e9 d\u2019interf\u00e9rer le moins possible avec la topographie visuelle du paysage a conduit \u00e0 poser la maison au sol et \u00e0 trouver des solutions pour la fa\u00e7ade et la toiture en contact direct avec l\u2019environnement. L\u2019id\u00e9e d\u2019un \u00ab b\u00e2timent squat \u00bb a guid\u00e9 les d\u00e9cisions concernant le volume, la position, l\u2019occupation, l\u2019aspect ext\u00e9rieur et le rev\u00eatement de fa\u00e7ade.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-9246 alignnone aligncenter\" src=\"http:\/\/mjarc.com\/wp-content\/uploads\/2023\/07\/piscina_mjarc-1000x667.jpg\" alt=\"\" width=\"1060\" height=\"707\" srcset=\"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/07\/piscina_mjarc-1000x667.jpg 1000w, https:\/\/mjarc.com\/wp-content\/uploads\/2023\/07\/piscina_mjarc-768x512.jpg 768w, https:\/\/mjarc.com\/wp-content\/uploads\/2023\/07\/piscina_mjarc-1536x1024.jpg 1536w, https:\/\/mjarc.com\/wp-content\/uploads\/2023\/07\/piscina_mjarc-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1060px) 100vw, 1060px\" \/><\/h3>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9249 alignnone aligncenter\" src=\"http:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/JFFC340432.png\" alt=\"\" width=\"1059\" height=\"706\" srcset=\"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/JFFC340432.png 800w, https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/JFFC340432-768x512.png 768w\" sizes=\"auto, (max-width: 1059px) 100vw, 1059px\" \/><\/h3>\n<h3><\/h3>\n<p>&nbsp;<\/p>\n<h3>Mat\u00e9riaux de construction pour les maisons modernes \u00e0 un \u00e9tage<\/h3>\n<p>Les maisons modernes se caract\u00e9risent par une architecture aux lignes droites, des formes g\u00e9om\u00e9triques simples et une fa\u00e7ade \u00e0 la structure lin\u00e9aire et aux d\u00e9tails distinctifs. Ces maisons peuvent \u00eatre bas\u00e9es sur une construction traditionnelle ou <a href=\"https:\/\/mjarc.com\/fr\/maisons-prefabriquees-ou-maisons-modulaires-perspective-architecturale\/\" target=\"_blank\" rel=\"noopener\">pr\u00e9fabriqu\u00e9e<\/a>, avec un large \u00e9ventail de mat\u00e9riaux et de techniques de construction qui doivent \u00eatre \u00e9valu\u00e9s lors de la phase de conception.<\/p>\n<p>Le choix des mat\u00e9riaux ainsi que la technique de construction \u00e0 adopter jouent un r\u00f4le essentiel non seulement dans l&rsquo;int\u00e9gration de votre maison mais \u00e9galement dans sa performance <a href=\"https:\/\/mjarc.com\/fr\/certification-energetique\/\" target=\"_blank\" rel=\"noopener\">\u00e9nerg\u00e9tique<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8461 aligncenter\" src=\"http:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-768x1024.jpg\" alt=\"\" width=\"769\" height=\"1025\" srcset=\"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-768x1024.jpg 768w, https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-225x300.jpg 225w, https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-1152x1536.jpg 1152w, https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-1536x2048.jpg 1536w, https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-scaled.jpg 1920w\" sizes=\"auto, (max-width: 769px) 100vw, 769px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\">Fig.3 Image tir\u00e9e d&rsquo;un projet MJARC construit dans une structure pr\u00e9fabriqu\u00e9e en bois.<\/span><\/p>\n<h3><\/h3>\n<h3><\/h3>\n<p>L\u2019efficacit\u00e9 \u00e9nerg\u00e9tique est un facteur cl\u00e9 de l\u2019architecture moderne, et les maisons \u00e0 un \u00e9tage ne font pas exception. Quelques aspects \u00e0 consid\u00e9rer:<\/p>\n<ul>\n<li><strong>Certification \u00e9nerg\u00e9tique:<\/strong> au Portugal, bien qu&rsquo;il existe des situations dans lesquelles il existe une exemption de certification \u00e9nerg\u00e9tique, celle-ci est obligatoire pour les b\u00e2timents r\u00e9sidentiels. Les maisons \u00e0 un \u00e9tage peuvent atteindre des notes \u00e9lev\u00e9es gr\u00e2ce \u00e0 l\u2019utilisation de mat\u00e9riaux et de techniques de construction durables;<\/li>\n<li><strong>\u00c9nergies renouvelables:<\/strong> l&rsquo;installation de panneaux solaires pour produire de l&rsquo;\u00e9lectricit\u00e9 et chauffer de l&rsquo;eau est une option courante qui permet de r\u00e9duire la consommation d&rsquo;\u00e9nergie;<\/li>\n<li><strong>Isolation thermique et acoustique:<\/strong> une isolation de haute qualit\u00e9 contribue au confort int\u00e9rieur et \u00e0 l&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique, en minimisant les d\u00e9perditions de chaleur en hiver et les apports de chaleur en \u00e9t\u00e9;<\/li>\n<li><strong>Orientation correcte du solarium de la propri\u00e9t\u00e9.<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Pr\u00eat \u00e0 aller de l&rsquo;avant avec votre maison \u00e0 un \u00e9tage?<\/h3>\n<p>Si vous envisagez de construire une maison de plain-pied au Portugal, vous pouvez compter sur le soutien de <a href=\"https:\/\/mjarc.com\/fr\/contacts\/\">l&rsquo;\u00e9quipe d&rsquo;architectes de MJARC<\/a> pour garantir que tous les aspects techniques et juridiques soient trait\u00e9s avec succ\u00e8s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsqu\u2019on envisage de construire une maison, plusieurs points de d\u00e9cision cruciaux se posent. L\u2019une des plus importantes consiste \u00e0 d\u00e9finir le projet de logement : quelle sera sa taille, combien de chambres et de salles de bains il comprendra, s\u2019il aura un jardin et s\u2019il s\u2019agira d\u2019une maison de plain-pied ou plus. Dans cet article, [&hellip;]<\/p>\n<p class=\"read-more\"><a class=\"button\" href=\"https:\/\/mjarc.com\/fr\/maisons-modernes-a-un-etage-exemples-materiaux-et-certification\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":8463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[32,51],"tags":[621,622,623,624,625],"class_list":["post-9465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquitetura-fr","category-eficiencia-fr","tag-maisons-de-plain-pied","tag-materiaux-de-construction","tag-maisons-modernes-a-un-etage","tag-certifications","tag-durabilite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez des exemples, des mat\u00e9riaux et des certifications pour des maisons \u00e0 un \u00e9tage. Conseils utiles pour une construction id\u00e9ale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez des exemples, des mat\u00e9riaux et des certifications pour des maisons \u00e0 un \u00e9tage. Conseils utiles pour une construction id\u00e9ale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Mjarc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mjarc.arquitectos\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-22T15:13:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-14T12:33:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mjarc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mjarc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/\"},\"author\":{\"name\":\"Mjarc\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/person\\\/4b3afbd73b7217bd7abd6435d1e05f2e\"},\"headline\":\"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification\",\"datePublished\":\"2023-11-22T15:13:31+00:00\",\"dateModified\":\"2023-12-14T12:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/\"},\"wordCount\":670,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_1806-scaled.jpg\",\"keywords\":[\"maisons de plain-pied\",\"Mat\u00e9riaux de construction\",\"maisons modernes \u00e0 un \u00e9tage\",\"Certifications\",\"durabilit\u00e9\"],\"articleSection\":[\"Architecture\",\"Efficacit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/\",\"url\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/\",\"name\":\"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_1806-scaled.jpg\",\"datePublished\":\"2023-11-22T15:13:31+00:00\",\"dateModified\":\"2023-12-14T12:33:36+00:00\",\"description\":\"D\u00e9couvrez des exemples, des mat\u00e9riaux et des certifications pour des maisons \u00e0 un \u00e9tage. Conseils utiles pour une construction id\u00e9ale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_1806-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_1806-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"MJARC - Flip Book - Apresenta\u00e7\u00e3o arquitetura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/casas-terreas-modernas-exemplos-materiais-certificacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/\",\"name\":\"Mjarc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#organization\",\"name\":\"Mjarc\",\"url\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo_black_1.png\",\"contentUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo_black_1.png\",\"width\":130,\"height\":130,\"caption\":\"Mjarc\"},\"image\":{\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mjarc.arquitectos\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mjarc.arq\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/#\\\/schema\\\/person\\\/4b3afbd73b7217bd7abd6435d1e05f2e\",\"name\":\"Mjarc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/litespeed\\\/avatar\\\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963\",\"url\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/litespeed\\\/avatar\\\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963\",\"contentUrl\":\"https:\\\/\\\/mjarc.com\\\/wp-content\\\/litespeed\\\/avatar\\\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963\",\"caption\":\"Mjarc\"},\"url\":\"https:\\\/\\\/mjarc.com\\\/fr\\\/author\\\/mjarc1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification","description":"D\u00e9couvrez des exemples, des mat\u00e9riaux et des certifications pour des maisons \u00e0 un \u00e9tage. Conseils utiles pour une construction id\u00e9ale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/","og_locale":"fr_FR","og_type":"article","og_title":"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification","og_description":"D\u00e9couvrez des exemples, des mat\u00e9riaux et des certifications pour des maisons \u00e0 un \u00e9tage. Conseils utiles pour une construction id\u00e9ale.","og_url":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/","og_site_name":"Mjarc","article_publisher":"https:\/\/www.facebook.com\/mjarc.arquitectos\/","article_published_time":"2023-11-22T15:13:31+00:00","article_modified_time":"2023-12-14T12:33:36+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-scaled.jpg","type":"image\/jpeg"}],"author":"Mjarc","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mjarc","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/#article","isPartOf":{"@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/"},"author":{"name":"Mjarc","@id":"https:\/\/mjarc.com\/fr\/#\/schema\/person\/4b3afbd73b7217bd7abd6435d1e05f2e"},"headline":"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification","datePublished":"2023-11-22T15:13:31+00:00","dateModified":"2023-12-14T12:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/"},"wordCount":670,"commentCount":0,"publisher":{"@id":"https:\/\/mjarc.com\/fr\/#organization"},"image":{"@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/#primaryimage"},"thumbnailUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-scaled.jpg","keywords":["maisons de plain-pied","Mat\u00e9riaux de construction","maisons modernes \u00e0 un \u00e9tage","Certifications","durabilit\u00e9"],"articleSection":["Architecture","Efficacit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/","url":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/","name":"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification","isPartOf":{"@id":"https:\/\/mjarc.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/#primaryimage"},"image":{"@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/#primaryimage"},"thumbnailUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-scaled.jpg","datePublished":"2023-11-22T15:13:31+00:00","dateModified":"2023-12-14T12:33:36+00:00","description":"D\u00e9couvrez des exemples, des mat\u00e9riaux et des certifications pour des maisons \u00e0 un \u00e9tage. Conseils utiles pour une construction id\u00e9ale.","breadcrumb":{"@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/#primaryimage","url":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-scaled.jpg","contentUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/11\/IMG_1806-scaled.jpg","width":1920,"height":2560,"caption":"MJARC - Flip Book - Apresenta\u00e7\u00e3o arquitetura"},{"@type":"BreadcrumbList","@id":"https:\/\/mjarc.com\/casas-terreas-modernas-exemplos-materiais-certificacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mjarc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Maisons modernes \u00e0 un \u00e9tage \u2013 exemples, mat\u00e9riaux et certification"}]},{"@type":"WebSite","@id":"https:\/\/mjarc.com\/fr\/#website","url":"https:\/\/mjarc.com\/fr\/","name":"Mjarc","description":"","publisher":{"@id":"https:\/\/mjarc.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mjarc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mjarc.com\/fr\/#organization","name":"Mjarc","url":"https:\/\/mjarc.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mjarc.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/logo_black_1.png","contentUrl":"https:\/\/mjarc.com\/wp-content\/uploads\/2023\/08\/logo_black_1.png","width":130,"height":130,"caption":"Mjarc"},"image":{"@id":"https:\/\/mjarc.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mjarc.arquitectos\/","https:\/\/www.instagram.com\/mjarc.arq\/"]},{"@type":"Person","@id":"https:\/\/mjarc.com\/fr\/#\/schema\/person\/4b3afbd73b7217bd7abd6435d1e05f2e","name":"Mjarc","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mjarc.com\/wp-content\/litespeed\/avatar\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963","url":"https:\/\/mjarc.com\/wp-content\/litespeed\/avatar\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963","contentUrl":"https:\/\/mjarc.com\/wp-content\/litespeed\/avatar\/bbed492adff5646ba02f6c482eda4fc3.jpg?ver=1778177963","caption":"Mjarc"},"url":"https:\/\/mjarc.com\/fr\/author\/mjarc1\/"}]}},"_links":{"self":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts\/9465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/comments?post=9465"}],"version-history":[{"count":5,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts\/9465\/revisions"}],"predecessor-version":[{"id":9582,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/posts\/9465\/revisions\/9582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/media\/8463"}],"wp:attachment":[{"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/media?parent=9465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/categories?post=9465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mjarc.com\/fr\/wp-json\/wp\/v2\/tags?post=9465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}